{"id":272,"date":"2023-02-08T20:16:43","date_gmt":"2023-02-08T18:16:43","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/02\/08\/ritual-a-la-fabra-i-coats\/"},"modified":"2023-02-08T20:16:43","modified_gmt":"2023-02-08T18:16:43","slug":"ritual-a-la-fabra-i-coats","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/02\/08\/ritual-a-la-fabra-i-coats\/","title":{"rendered":"RITUAL a la FABRA I COATS"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/2023\/02\/08\/ritual-a-la-fabra-i-coats\/\">Martina Rogers EN RESiD\u00c8NCiA<\/a><\/p>\n<div>\n<p><strong><em>D\u2019uns petits amulets,<br \/>en guardem una vida sencera plena de records i viv\u00e8ncies.<\/em><\/strong><\/p>\n<p>Tot comen\u00e7a com qualsevol altre dia\u2026 estic dins l\u2019institut envoltat dels companys i amics de la classe; just sona la m\u00fasica que transmet el missatge d\u2019inici de l\u2019hora del pati. Em dirigeixo, baixant les escales, a l\u2019entrada principal, on ens havien convocat el dia abans. Arribo al lloc de trobada i, mentre repassen la llista d\u2019alumnes, acabo d\u2019esmorzar. Acaben d\u2019organitzar la sortida i ens dirigim plegats tota la classe d\u2019expressi\u00f3 art\u00edstica, a la Fabra i Coats.<strong><em><br \/><\/em><\/strong><\/p>\n<figure class=\"is-layout-flex wp-block-gallery-5 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"1024\" data-id=\"82\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-640x1024.jpg\" alt=\"\" class=\"wp-image-82\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-640x1024.jpg 640w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-188x300.jpg 188w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-768x1229.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-960x1536.jpg 960w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-1280x2048.jpg 1280w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_120138-scaled.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/figure>\n<\/figure>\n<p>Arribo al dest\u00ed. All\u00e0 ens asseiem a terra en rotllana, i com a mi, ens donen a tots un llapis de carbonet. Al centre del cercle col\u00b7loquen unes boniques espelmes. Sembla estar tot a punt\u2026 Aleshores, la Martina ens explica d\u2019una manera senzilla el tipus de ritual que anem a fer. <\/p>\n<figure class=\"is-layout-flex wp-block-gallery-7 wp-block-gallery has-nested-images columns-default is-cropped\"><\/figure>\n<figure class=\"is-layout-flex wp-block-gallery-9 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"1024\" data-id=\"84\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-640x1024.jpg\" alt=\"\" class=\"wp-image-84\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-640x1024.jpg 640w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-188x300.jpg 188w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-768x1229.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-960x1536.jpg 960w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-1280x2048.jpg 1280w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121304-scaled.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/figure>\n<\/figure>\n<ul>\n<li>Una conversa divertida, tranquil\u00b7la, distesa, que ajuda a pensar i a reflexionar; una bonica estona. Dibuixem a terra, escrivim prop\u00f2sits per aquest nou any sobre papers blancs\u2026 Aquests escrits els cremem al foc de les espelmes com a part del ritual\u2026 i sobretot, el que m\u00e9s m\u2019apassiona, agafem un amulet fet per la Martina i despr\u00e9s cadasc\u00fa en dissenya un amb diferents tipus de fang (mat\u00e8ria i color).<\/li>\n<\/ul>\n<figure class=\"is-layout-flex wp-block-gallery-11 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"1024\" data-id=\"85\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-640x1024.jpg\" alt=\"\" class=\"wp-image-85\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-640x1024.jpg 640w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-188x300.jpg 188w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-768x1229.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-960x1536.jpg 960w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-1280x2048.jpg 1280w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_121448-scaled.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/figure>\n<\/figure>\n<figure class=\"is-layout-flex wp-block-gallery-13 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"1024\" data-id=\"86\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-640x1024.jpg\" alt=\"\" class=\"wp-image-86\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-640x1024.jpg 640w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-188x300.jpg 188w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-768x1229.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-960x1536.jpg 960w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-1280x2048.jpg 1280w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2023\/wp-content\/uploads\/2023\/02\/IMG_20221220_123116-scaled.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/figure>\n<\/figure>\n<ul>\n<li>Una bonica classe on he apr\u00e8s d\u2019una forma entretinguda i diferent, com petits objectes poden contenir un munt de records i viv\u00e8ncies. El sol fet de mirar-los en un futur em poden ajudar a recordar moments importants. La classe arriba a la seva fi; per\u00f2 la viv\u00e8ncia i l\u2019ensenyan\u00e7a d\u2019avui se\u2019m guarda dins meu\u2026 com un bonic r\u00e8cord que atresorar\u00e9 com un preuat amulet.<\/li>\n<li>Moltes gr\u00e0cies per aquest dia!!<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Martina Rogers EN RESiD\u00c8NCiA D\u2019uns petits amulets,en guardem una vida sencera plena de records i viv\u00e8ncies. Tot comen\u00e7a com qualsevol altre dia\u2026 estic dins l\u2019institut envoltat dels companys i amics de la classe; just sona la m\u00fasica que transmet el missatge d\u2019inici de l\u2019hora del pati. Em dirigeixo, baixant les escales, a l\u2019entrada &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/02\/08\/ritual-a-la-fabra-i-coats\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abRITUAL a la FABRA I COATS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-272","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/272\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/media?parent=272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/categories?post=272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/tags?post=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}