{"id":284,"date":"2023-02-21T13:29:32","date_gmt":"2023-02-21T11:29:32","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/02\/21\/una-contaminacio-espectacular\/"},"modified":"2023-02-21T13:29:32","modified_gmt":"2023-02-21T11:29:32","slug":"una-contaminacio-espectacular","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/02\/21\/una-contaminacio-espectacular\/","title":{"rendered":"Una contaminaci\u00f3 espectacular!"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/2023\/02\/21\/una-contaminacio-espectacular\/\">Urati laboratori EN RESiD\u00c8NCiA<\/a><\/p>\n<div>\n<p>Una jornada de Contaminaci\u00f3 amb molta il\u00b7lusi\u00f3, alguns nervis, per\u00f2 molt ben gestionada pel propi alumnat. <\/p>\n<p>\u201cVam comen\u00e7ar el dia amb molta energia, posant tots els materials a l\u2019espai \u00c0gora del nostre centre, per poder mostrar la feina feta a l\u2019alumnat de 5\u00e8 i 6\u00e8 de prim\u00e0ria\u201d que com b\u00e9 diu tamb\u00e9 l\u2019\u00c8lia; \u201c\u2026 les nenes i les nens van parar molta atenci\u00f3 a les nostres explicacions\u201d i ens va ajudar molt a poder ensenyar tot el que hav\u00edem treballat fins al moment.<\/p>\n<p>El primer va ser fer una sessi\u00f3 en la que vam programar tot el que vol\u00edem mostrar. Fer una pluja d\u2019idees, concretar l\u2019espai, organitzar les tasques\u2026 tot pensat per poder preparar-ho el millor possible.<\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230126_103933-1024x768.jpg\" alt=\"\" class=\"wp-image-49\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230126_103933-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230126_103933-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230126_103933-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230126_103933-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230126_103933-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><figcaption class=\"wp-element-caption\">Organitzaci\u00f3 de la jornada <\/figcaption><\/figure>\n<p>El mateix dia de la Contaminaci\u00f3, va ser molt emocionant, la Yue ens ho explica aix\u00ed; \u201cEn el moment de  la contaminaci\u00f3 jo era la guia i la Tyra m\u2019acompanyava. Durant la primera ronda jo estava molt nerviosa en pensar que alguna cosa podria anar malament, per\u00f2 no! En acabar vaig pensar que havia sortit excel\u00b7lent.\u00a0 Primer vam acompanyar els de cinqu\u00e8 de prim\u00e0ria en l\u2019espai de les ulleres virtuals i ens vam repartir les tasques; la Tyra acompanyant les persones per veure si estaven b\u00e9\u00a0 en l\u2019espai de les ulleres virtuals i jo acompanyant als altres 4 nens a parlar sobre els escrits i les activitats que hav\u00edem fet al llarg del trimestre. Em vaig quedar sense saber qu\u00e8 dir i la Marisa em va ajuda a explicar. <\/p>\n<p>Quan vam acabar de fer aix\u00f2, ven r\u00e0pidament vam anar cap a la sala de les histories i els nens i les nenes s\u2019ho va passar molt b\u00e9 i van riure molt perqu\u00e8 les hist\u00f2ries eren s\u00faper divertides i en vam poder llegir unes quantes.<\/p>\n<p>Despr\u00e9s, a la sala de l\u2019\u00e0udio visual, els va agradar molt pel v\u00eddeo en el que sortia un petit  mono i l\u2019\u00e0nec nadant amb una m\u00fasica i uns sons de fons molt relacionat amb les imatges del v\u00eddeo. Al final vaig perdre el veu per parlar molt.\u201d<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093319-1024x768.jpg\" alt=\"\" class=\"wp-image-50\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093319-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093319-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093319-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093319-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093319-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><figcaption class=\"wp-element-caption\">Provant les ulleres virtuals<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093234-1024x768.jpg\" alt=\"\" class=\"wp-image-51\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093234-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093234-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093234-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093234-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093234-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><figcaption class=\"wp-element-caption\">Llegint els relats que hav\u00edem escrit<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093214-1024x768.jpg\" alt=\"\" class=\"wp-image-52\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093214-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093214-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093214-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093214-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093214-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><figcaption class=\"wp-element-caption\">La zona de l\u2019\u00e0udio visual va ser un \u00e8xit<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093307-768x1024.jpg\" alt=\"\" class=\"wp-image-55\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093307-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093307-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093307-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093307-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/eixample2023\/wp-content\/uploads\/2023\/02\/20230209_093307-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><figcaption class=\"wp-element-caption\">I la maqueta del nostre futur producte final!!!<\/figcaption><\/figure>\n<p>No nom\u00e9s va venir l\u2019alumnat de 5\u00e8 i 6\u00e8 de prim\u00e0ria, tamb\u00e9 el professorat de secund\u00e0ria, prim\u00e0ria i infantil va poder visitar l\u2019espai i, com no podria ser d\u2019una altra manera, vam convidar a la resta de companys i companyes de 3r d\u2019ESO!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Urati laboratori EN RESiD\u00c8NCiA Una jornada de Contaminaci\u00f3 amb molta il\u00b7lusi\u00f3, alguns nervis, per\u00f2 molt ben gestionada pel propi alumnat. \u201cVam comen\u00e7ar el dia amb molta energia, posant tots els materials a l\u2019espai \u00c0gora del nostre centre, per poder mostrar la feina feta a l\u2019alumnat de 5\u00e8 i 6\u00e8 de prim\u00e0ria\u201d que com &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/02\/21\/una-contaminacio-espectacular\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abUna contaminaci\u00f3 espectacular!\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-284","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/284\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/media?parent=284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/categories?post=284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/tags?post=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}