{"id":1006,"date":"2024-03-07T12:02:04","date_gmt":"2024-03-07T10:02:04","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/07\/sesion-16-14-2-2024\/"},"modified":"2024-03-07T12:02:04","modified_gmt":"2024-03-07T10:02:04","slug":"sesion-16-14-2-2024","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/07\/sesion-16-14-2-2024\/","title":{"rendered":"SESI\u00d3N 16- 14\/2\/2024"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/sesion-16-14-2-2024\/\">Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol<\/a><\/p>\n<div>\n<p>El d\u00eda de San Valent\u00edn fue la sesi\u00f3n antes de la presentaci\u00f3n (sesi\u00f3n abierta) a los profesores. <\/p>\n<p>En esta ocasi\u00f3n no nos fuimos al Casal Can Travi, sino que nos instalamos en el gimnasio del instituto. All\u00ed, llegamos al acuerdo de hacer media sesi\u00f3n para acabar de retocar la muestra, los \u00faltimos detalles, sobre todo la estructura que seguir\u00edamos. Y eso es lo que hicimos.<\/p>\n<p>Despu\u00e9s, subimos a clase y nos pusimos en grupos.  Creamos la presentaci\u00f3n y fuimos explic\u00e1ndole a Lautaro lo que har\u00edamos para que nos diera su visto bueno. Cuando ya trabaj\u00e1bamos, Lautaro nos fue llamando uno por uno para habla con nosotros, y decirnos lo que hac\u00edamos bien y lo que le gustaba de nosotros, pero tambi\u00e9n los puntos que deb\u00edamos mejorar y pulir a la hora de llevarlo todo a la pr\u00e1ctica.<\/p>\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/IMG_2018-1024x683.jpg\" alt=\"\" class=\"wp-image-505\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/IMG_2018-1024x683.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/IMG_2018-300x200.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/IMG_2018-768x512.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/IMG_2018-1536x1024.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/IMG_2018-2048x1365.jpg 2048w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol El d\u00eda de San Valent\u00edn fue la sesi\u00f3n antes de la presentaci\u00f3n (sesi\u00f3n abierta) a los profesores. En esta ocasi\u00f3n no nos fuimos al Casal Can Travi, sino que nos instalamos en el gimnasio del instituto. All\u00ed, llegamos al acuerdo de hacer media sesi\u00f3n para &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/07\/sesion-16-14-2-2024\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSESI\u00d3N 16- 14\/2\/2024\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1006","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}