{"id":1008,"date":"2024-03-07T18:44:17","date_gmt":"2024-03-07T16:44:17","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/07\/la-facana-de-la-nostre-casa\/"},"modified":"2024-03-07T18:44:17","modified_gmt":"2024-03-07T16:44:17","slug":"la-facana-de-la-nostre-casa","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/07\/la-facana-de-la-nostre-casa\/","title":{"rendered":"La fa\u00e7ana de la nostre casa"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/bastida2024\/la-facana-de-la-nostre-casa\/\">Dom\u00e8nec EN RESiD\u00c8NCiA a l&#8217;Institut La Bastida<\/a><\/p>\n<div>\n<p>Amb en Dom\u00e8nec vam dibuixar la fa\u00e7ana de la nostre casa.<br \/>La fa\u00e7ana d\u2019una casa \u00e9s la part exterior visible, incloent portes, finestres i detalls decoratius. \u00c9s crucial per al disseny i l\u2019est\u00e8tica de l\u2019edifici, reflectint l\u2019estil i les prefer\u00e8ncies dels propietaris o dissenyadors.<br \/>Per dibuixar la fa\u00e7ana de casa, cadasc\u00fa de nosaltres va cercar casa seva a Google maps que ens va mostrar la imatge de la nostra casa i la vam poder reproduir.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Dom\u00e8nec EN RESiD\u00c8NCiA a l&#8217;Institut La Bastida Amb en Dom\u00e8nec vam dibuixar la fa\u00e7ana de la nostre casa.La fa\u00e7ana d\u2019una casa \u00e9s la part exterior visible, incloent portes, finestres i detalls decoratius. \u00c9s crucial per al disseny i l\u2019est\u00e8tica de l\u2019edifici, reflectint l\u2019estil i les prefer\u00e8ncies dels propietaris o dissenyadors.Per dibuixar la fa\u00e7ana &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/07\/la-facana-de-la-nostre-casa\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abLa fa\u00e7ana de la nostre casa\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1008","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=1008"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1008\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=1008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=1008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=1008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}