{"id":1040,"date":"2024-04-01T20:24:08","date_gmt":"2024-04-01T18:24:08","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/04\/01\/la-sessio-oberta\/"},"modified":"2024-04-01T20:24:08","modified_gmt":"2024-04-01T18:24:08","slug":"la-sessio-oberta","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/04\/01\/la-sessio-oberta\/","title":{"rendered":"LA SESSI\u00d3 OBERTA"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/ribera2024\/la-sessio-oberta\/\">Rodrigo Lavi\u00f1a EN RESiD\u00c8NCiA a l&#8217;Institut La Ribera<\/a><\/p>\n<div>\n<p>Una tarda que no oblidarem a l\u2019<strong>Institut La Ribera<\/strong> de Montcada i Reixac: nervis, emocions i repte assolit. Us deixem el reportatge que ha fet el diari local <strong>La Veu <\/strong>de Montcada sobre la sessi\u00f3 oberta. <\/p>\n<p>Gr\u00e0cies a tot el professorat i institucions que van dedicar-nos el seu temps a escoltar-nos, donar suport  i ajudar a millorar: <a href=\"https:\/\/laveu.cat\/etiqueta\/en-residencia\/\" data-type=\"link\" data-id=\"https:\/\/laveu.cat\/etiqueta\/en-residencia\/\">https:\/\/laveu.cat\/etiqueta\/en-residencia\/<\/a>. Gr\u00e0cies a la classe de 3r d\u2019ESO D\u2019En Resid\u00e8ncia que es va mostrar en tot moment treballador, implicat, responsable i motivat.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/laveu.cat\/etiqueta\/en-residencia\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"471\" data-id=\"348\" src=\"https:\/\/blocsenresidencia.bcn.cat\/ribera2024\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2024-04-01-201649.png\" alt=\"\" class=\"wp-image-348\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/ribera2024\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2024-04-01-201649.png 850w, https:\/\/blocsenresidencia.bcn.cat\/ribera2024\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2024-04-01-201649-300x166.png 300w, https:\/\/blocsenresidencia.bcn.cat\/ribera2024\/wp-content\/uploads\/2024\/04\/Captura-de-pantalla-2024-04-01-201649-768x426.png 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/a><\/figure>\n<\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Rodrigo Lavi\u00f1a EN RESiD\u00c8NCiA a l&#8217;Institut La Ribera Una tarda que no oblidarem a l\u2019Institut La Ribera de Montcada i Reixac: nervis, emocions i repte assolit. Us deixem el reportatge que ha fet el diari local La Veu de Montcada sobre la sessi\u00f3 oberta. Gr\u00e0cies a tot el professorat i institucions que van &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/04\/01\/la-sessio-oberta\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abLA SESSI\u00d3 OBERTA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1040","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=1040"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1040\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=1040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=1040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=1040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}