{"id":1042,"date":"2024-04-04T11:12:27","date_gmt":"2024-04-04T09:12:27","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/04\/04\/sesion-abierta-20-2-24\/"},"modified":"2024-04-04T11:12:27","modified_gmt":"2024-04-04T09:12:27","slug":"sesion-abierta-20-2-24","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/04\/04\/sesion-abierta-20-2-24\/","title":{"rendered":"Sesi\u00f3n abierta \u2013 20\/2\/24"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/sesion-abierta-20-2-24\/\">Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol<\/a><\/p>\n<div>\n<p>La sesi\u00f3n abierta es un momento importante del proyecto ya que es cuando tomamos conciencia de todo el recorrido y mostramos parte del proceso a los profesores del instituto. Exponerse a los otros siempre causa respeto, pero estamos ilusionados porque hemos trabajado mucho y vamos a dar lo mejor de nosotros.<\/p>\n<p>Empezamos preparando el d\u00eda yendo a la hora del patio a comprar comida y bebida para hacer un pica pica despu\u00e9s de la actuaci\u00f3n. La idea es general un espacio distentido despu\u00e9s de la sesi\u00f3n para poder charlar e intercambiar impresiones con los asistentes.<\/p>\n<p> Despu\u00e9s, hicimos una clase m\u00e1s para ensayar y bajamos para acabar de memorizar algunas inetervenciones de la exposici\u00f3n y acabar de pulir el fragmento de la pieza que \u00edbamos a bailar.<\/p>\n<p>Poco a poco iba pasando el tiempo y se acercaba la hora de la verdad. Aunque no lo parezciera, ibamos poni\u00e9ndonos m\u00e1s nerviosos. <\/p>\n<p>Cuando menos lo esperamos, fueron llegando los profesores y, en un momento, ya est\u00e1bamos todos. <\/p>\n<p>Empezamos con la exposici\u00f3n. Todos hablamos y nos compaginamos bien para que fuera din\u00e1mico.<\/p>\n<p>Fue todo bien y llegamos al momento de la muestra, pero, antes de empezar y con todos los profesores abajo, Lautaro nos sac\u00f3 del gimnasio y nos dijo que ten\u00edamos un compromiso con nosotros mismos y tambi\u00e9n con \u00e9l.\u00a0Fue un momento muy emocionante de conexi\u00f3n con el grupo.<\/p>\n<p>Volvimos al gimnasio a hacer la pieza, todos estaban impacientes ya as\u00ed que empezamos. <\/p>\n<p>En nuestra pieza, cada uno de nosotros se va colocando aleatoriamente en el espacio y parec\u00eda que nadie quisiera salir el primero: hab\u00eda muchos nervios. Pero, cuando ya hab\u00edmos salido todos y empezamos a movernos, poco a poco nos fuimos metiendo en la obra y los nervios se fueron yendo. <\/p>\n<p>Fue una muy buena actuaci\u00f3n y acabamos entre aplausos.<\/p>\n<p>Retomamos la exposici\u00f3n con algunos detalles m\u00e1s de la obre y tuvimos la oportunidad de responder alguna pregunta. <\/p>\n<p>Acabamos con el pica pica que hab\u00edamos preparado. La verdad es que despu\u00e9s del trabajo vino bien recuperarse con esa comida y bebida. <\/p>\n<p>En resumen, fue una experiencia que afrontamos con nervios, pero que acabamos disfrutando mucho y tambi\u00e9n creemos que fue sorprendente, sobre todo para los profesores.<\/p>\n<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"528\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-%C2%A9-Mila-Ercoli_42-2-1024x683.jpg\" alt=\"\" class=\"wp-image-528\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_42-2-1024x683.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_42-2-300x200.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_42-2-768x512.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_42-2-1536x1024.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_42-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"529\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-%C2%A9-Mila-Ercoli_41-2-1024x683.jpg\" alt=\"\" class=\"wp-image-529\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_41-2-1024x683.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_41-2-300x200.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_41-2-768x512.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_41-2-1536x1024.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_41-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"524\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-%C2%A9-Mila-Ercoli_22-2-1024x683.jpg\" alt=\"\" class=\"wp-image-524\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_22-2-1024x683.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_22-2-300x200.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_22-2-768x512.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_22-2-1536x1024.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_22-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"523\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-%C2%A9-Mila-Ercoli_13-1-1024x683.jpg\" alt=\"\" class=\"wp-image-523\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_13-1-1024x683.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_13-1-300x200.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_13-1-768x512.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_13-1-1536x1024.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_13-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"531\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-%C2%A9-Mila-Ercoli_12-2-1024x683.jpg\" alt=\"\" class=\"wp-image-531\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_12-2-1024x683.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_12-2-300x200.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_12-2-768x512.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_12-2-1536x1024.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/03\/En-Residencia_Lautaro-Reyes-\u00a9-Mila-Ercoli_12-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol La sesi\u00f3n abierta es un momento importante del proyecto ya que es cuando tomamos conciencia de todo el recorrido y mostramos parte del proceso a los profesores del instituto. Exponerse a los otros siempre causa respeto, pero estamos ilusionados porque hemos trabajado mucho y vamos &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/04\/04\/sesion-abierta-20-2-24\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSesi\u00f3n abierta \u2013 20\/2\/24\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1042","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/1042\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=1042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}