{"id":840,"date":"2023-11-05T16:01:56","date_gmt":"2023-11-05T14:01:56","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2023\/11\/05\/benvinguts-al-nostre-bloc\/"},"modified":"2023-11-05T16:01:56","modified_gmt":"2023-11-05T14:01:56","slug":"benvinguts-al-nostre-bloc","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2023\/11\/05\/benvinguts-al-nostre-bloc\/","title":{"rendered":"BENVINGUTS AL NOSTRE BLOC!!"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/sants2024\/benvinguts-al-nostre-bloc\/\">Eu Manzanares EN RESiD\u00c8NCiA a l&#8217;Institut Sants<\/a><\/p>\n<div>\n<p>Ens fa molta il.lusi\u00f3 inaugurar el nostre bloc.<\/p>\n<p>QUI SOM? Som un grup d\u2019estudiants de 2n d\u2019ESO de l\u2019Institut Sants que hem escollit fer aquest projecte perqu\u00e8 ens va semblar molt interessant viure l\u2019experi\u00e8ncia de fer teatre amb una artista.<\/p>\n<p>Properament, us parlarem del que estem fent i com ens hem sentit en aquestes primeres sessions.<\/p>\n<p>FINS MOLT AVIAT!<\/p>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Eu Manzanares EN RESiD\u00c8NCiA a l&#8217;Institut Sants Ens fa molta il.lusi\u00f3 inaugurar el nostre bloc. QUI SOM? Som un grup d\u2019estudiants de 2n d\u2019ESO de l\u2019Institut Sants que hem escollit fer aquest projecte perqu\u00e8 ens va semblar molt interessant viure l\u2019experi\u00e8ncia de fer teatre amb una artista. Properament, us parlarem del que estem &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2023\/11\/05\/benvinguts-al-nostre-bloc\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abBENVINGUTS AL NOSTRE BLOC!!\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-840","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/840\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}