{"id":854,"date":"2023-11-16T14:15:25","date_gmt":"2023-11-16T12:15:25","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2023\/11\/16\/sesion-1-27-9-2023\/"},"modified":"2023-11-16T14:15:25","modified_gmt":"2023-11-16T12:15:25","slug":"sesion-1-27-9-2023","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2023\/11\/16\/sesion-1-27-9-2023\/","title":{"rendered":"Sesi\u00f3n 1 \u2013 27\/9\/2023"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/sesion-1-27-9-2023\/\">Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol<\/a><\/p>\n<div>\n<p>En esta sesi\u00f3n le hicimos una presentaci\u00f3n de nosotros a Lautaro y a la otra mediadora, M\u00f3nica; para que supiera un poco m\u00e1s de nosotros.\u00a0<\/p>\n<p>Luego, fuimos caminando hacia el Casal de Can Travi, el lugar donde har\u00edamos las sesiones de los mi\u00e9rcoles a partir de ahora, porqu\u00e9 el gimnasio del instituto est\u00e1 ocupado en esta franja. <\/p>\n<p>Una vez all\u00ed, nos pidi\u00f3 que busc\u00e1ramos en Internet el artista \u2018Kandinski\u2019. Escogimos un cuadro y nos fijamos en que este artista suele utilizar las figuras geom\u00e9tricas en todas sus pinturas e intentamos descifrar el significado que quer\u00eda transmitir con los colores.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"299\" height=\"169\" data-id=\"350\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/descarga.jpeg\" alt=\"\" class=\"wp-image-350\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" data-id=\"351\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/descarga-2.jpeg\" alt=\"\" class=\"wp-image-351\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/descarga-2.jpeg 225w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/descarga-2-150x150.jpeg 150w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/descarga-2-100x100.jpeg 100w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\"><\/figure>\n<\/figure>\n<p>Al acabar, nos pusimos todos en l\u00ednea y, con los ojos cerrados, nos imaginamos una figura geom\u00e9trica en nuestra mente, le dimos un color y a ello le agreg\u00e1bamos una palabra que lo representara.\u00a0 Cuando ya pas\u00f3 un rato, Lautaro, cogi\u00f3 un boli y una libreta para ir apunt\u00e1ndolos. Mientras lo expres\u00e1bamos tambi\u00e9n pudimos o\u00edr lo que el resto hab\u00eda pensado e imaginado.\u00a0<\/p>\n<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"396\" height=\"295\" src=\"https:\/\/lh7-us.googleusercontent.com\/J1TP5zUb-SvT6nQCz65yE1aIpTR82CSBSemU2RXh_CeN0YVi-_88LsPGIFRoof0WX0nmDbdZbts6cTfdcT_IAXan_peTNWkpZWgNffUdWSwsTv4Y3YLk1r9M0LX2yODrXmu234kENOF-6o-cvRU7m7s\"><\/p>\n<p><img decoding=\"async\" width=\"583.0298722505044\" height=\"416.0441405012299\" src=\"https:\/\/lh7-us.googleusercontent.com\/H9QloxfCiY-MCk6CyWtSkHC5kvu9Qj9osw4iUw2oyMgAhqeWexV91S4MnLCDQCpvFv8K0vINQcpDYQ-qIyPTCro9UbC03C-9SaiV5A34TGHV9OJO2UQu-J3y4Y-UG4afT-Wx0Lm2aSTNlJLNrUwqsQE\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/9MjghzdRR5sI-H2wPslOF8L0gCU3W_QohxDWshCfTrwwtYEgoiFSfq2Vd5FvZLqR8ovuXVBsR4ZqtVXxP6aR6cNSFvbX94dNagxwY7Ia4dfdHRoZWePK3ETnYXz7Thy-KtH54ODu-mwAndBGw7gx-0A\" width=\"258\" height=\"193\"><\/p>\n<p>Despu\u00e9s de aquella puesta en com\u00fan, empezamos una nueva actividad. Ten\u00edamos que imaginar que la sala se repart\u00eda en tres espacios (o estaciones): uno para observar, otro para pensar como representar\u00edamos nuestra figura y visualizarla y el \u00faltimo para representarla. Al principio nos dio mucha verg\u00fcenza y nadie se atrev\u00eda a moverse.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/Gx79wEjo_RiAshVaeZQP1vUVEQqLbtDgyPYMnsXYjeG-KHRQPgl4xrxbm3Tw5Z3W5X294czh7s--R9iLbinaX1NCEAC-VqhcisKxDg0pVhE5xLpdwncA2ieks32RJGyfTvGpYvhn-kBB6qHsY-MZbXc\" width=\"138\" height=\"152\"><\/p>\n<p>En conjunto, tenemos opiniones muy variadas de esta sesi\u00f3n, por una parte, fue interesante, una experiencia nueva y \u00fanica, por otro lado, pasamos verg\u00fcenza ajena y nos falt\u00f3 confianza entre nosotros, ya que, algunos no nos conocemos. <\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_131049-1024x766.jpg\" alt=\"\" class=\"wp-image-347\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_131049-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_131049-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_131049-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_131049-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_131049-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"348\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_124119-1024x766.jpg\" alt=\"\" class=\"wp-image-348\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_124119-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_124119-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_124119-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_124119-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_124119-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"349\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_1311212-1024x766.jpg\" alt=\"\" class=\"wp-image-349\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_1311212-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_1311212-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_1311212-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_1311212-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20230927_1311212-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol En esta sesi\u00f3n le hicimos una presentaci\u00f3n de nosotros a Lautaro y a la otra mediadora, M\u00f3nica; para que supiera un poco m\u00e1s de nosotros.\u00a0 Luego, fuimos caminando hacia el Casal de Can Travi, el lugar donde har\u00edamos las sesiones de los mi\u00e9rcoles a partir &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2023\/11\/16\/sesion-1-27-9-2023\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSesi\u00f3n 1 \u2013 27\/9\/2023\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-854","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=854"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/854\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}