{"id":931,"date":"2024-01-11T12:25:02","date_gmt":"2024-01-11T10:25:02","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/01\/11\/sesion-7-15-11-23\/"},"modified":"2024-01-11T12:25:02","modified_gmt":"2024-01-11T10:25:02","slug":"sesion-7-15-11-23","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/01\/11\/sesion-7-15-11-23\/","title":{"rendered":"SESI\u00d3N 7- 15\/11\/23"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/sesion-7-15-11-23\/\">Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol<\/a><\/p>\n<div>\n<p>En esta sesi\u00f3n llegamos puntuales, pero en el casal nos dijeron que no ten\u00edan sitio para nosotros, que no ten\u00edan prevista nuestra visita hasta la semana siguiente, as\u00ed que volvimos al instituto e hicimos la sesi\u00f3n en el patio y el gimnasio.<\/p>\n<p>Al llegar al instituto nos fuimos directamente al patio y, como de costumbre, hicimos un ejercicio de escritura; que consist\u00eda en pensar en tres conceptos y describirlos. En general, nos cost\u00f3 mucho encontrar un concepto y a\u00fan m\u00e1s describirlo.<\/p>\n<p>Despu\u00e9s de pensar en los conceptos, bajamos al gimnasio para representar eso que hab\u00edamos pensado. Pero antes, Lautaro nos hizo una introducci\u00f3n para mentalizarnos para la posterior actividad. Era, b\u00e1sicamente, la sencilla pero a la vez dif\u00edcil cuesti\u00f3n de mantenerse inm\u00f3vil, sin mover el cuerpo por ninguna raz\u00f3n, centr\u00e1ndose en la respiraci\u00f3n. <\/p>\n<p>Por \u00faltimo, cuanto acabamos ese ejercicio, comenzamos a representar los conceptos en dos grupos. Al representarlo, cambi\u00e1bamos lentamente las posiciones mientras el otro grupo miraba.<\/p>\n<p><\/p>\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_122210-1-1024x766.jpg\" alt=\"\" class=\"wp-image-417\" style=\"width:347px;height:auto\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_122210-1-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_122210-1-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_122210-1-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_122210-1-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_122210-1-2048x1532.jpg 2048w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_132126-1024x766.jpg\" alt=\"\" class=\"wp-image-419\" style=\"width:337px;height:auto\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_132126-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_132126-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_132126-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_132126-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2024\/01\/IMG_20231115_132126-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-video\"><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Lautaro Reyes EN RESiD\u00c8NCiA a l&#8217;Institut Narc\u00eds Monturiol En esta sesi\u00f3n llegamos puntuales, pero en el casal nos dijeron que no ten\u00edan sitio para nosotros, que no ten\u00edan prevista nuestra visita hasta la semana siguiente, as\u00ed que volvimos al instituto e hicimos la sesi\u00f3n en el patio y el gimnasio. Al llegar al &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/01\/11\/sesion-7-15-11-23\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSESI\u00d3N 7- 15\/11\/23\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-931","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=931"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/931\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}