{"id":996,"date":"2024-03-02T20:42:19","date_gmt":"2024-03-02T18:42:19","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/02\/visitem-el-mnac-i-veiem-lobra-de-lantonio\/"},"modified":"2024-03-02T20:42:19","modified_gmt":"2024-03-02T18:42:19","slug":"visitem-el-mnac-i-veiem-lobra-de-lantonio","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/02\/visitem-el-mnac-i-veiem-lobra-de-lantonio\/","title":{"rendered":"Visitem el MNAC i veiem l\u2019obra de l\u2019Antonio!"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/visitem-el-mnac-i-veiem-lobra-de-lantonio\/\">Antonio Ortega EN RESiD\u00c8NCiA a l&#8217;Institut Vall d&#8217;Hebron<\/a><\/p>\n<div>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"437\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_104020-1024x768.jpg\" alt=\"\" class=\"wp-image-437\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_104020-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_104020-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_104020-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_104020-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_104020-2048x1536.jpg 2048w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"438\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_105314-1024x768.jpg\" alt=\"\" class=\"wp-image-438\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_105314-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_105314-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_105314-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_105314-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_105314-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\">Ara cap al terrat i la sala oval !<\/h2>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"440\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110541-768x1024.jpg\" alt=\"\" class=\"wp-image-440\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110541-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110541-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110541-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110541-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110541-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"439\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110549-1024x768.jpg\" alt=\"\" class=\"wp-image-439\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110549-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110549-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110549-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110549-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_110549-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"441\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111601-1024x768.jpg\" alt=\"\" class=\"wp-image-441\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111601-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111601-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111601-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111601-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111601-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"442\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111615-768x1024.jpg\" alt=\"\" class=\"wp-image-442\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111615-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111615-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111615-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111615-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111615-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"444\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111758-1024x768.jpg\" alt=\"\" class=\"wp-image-444\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111758-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111758-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111758-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111758-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_111758-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"443\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112959-1024x768.jpg\" alt=\"\" class=\"wp-image-443\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112959-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112959-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112959-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112959-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112959-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"445\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112816-1024x768.jpg\" alt=\"\" class=\"wp-image-445\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112816-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112816-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112816-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112816-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_112816-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\">Ara cap al Zumzeig<\/h2>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"446\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121233-1024x768.jpg\" alt=\"\" class=\"wp-image-446\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121233-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121233-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121233-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121233-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121233-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"447\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121255-1024x768.jpg\" alt=\"\" class=\"wp-image-447\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121255-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121255-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121255-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121255-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_121255-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\">Ja hem arrivat, aqu\u00ed ser\u00e0 on presentarem el nostre projecte\u2026..<\/h2>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"448\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123533-1024x768.jpg\" alt=\"\" class=\"wp-image-448\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123533-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123533-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123533-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123533-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123533-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"449\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123810-1024x768.jpg\" alt=\"\" class=\"wp-image-449\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123810-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123810-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123810-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123810-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/03\/IMG_20240229_123810-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\">Sembla que alguns han caminat molt i\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..no estan gaire acostumats \u2026..uuuhhhhmmmmm!!!!!!<\/h2>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Antonio Ortega EN RESiD\u00c8NCiA a l&#8217;Institut Vall d&#8217;Hebron Ara cap al terrat i la sala oval ! Ara cap al Zumzeig Ja hem arrivat, aqu\u00ed ser\u00e0 on presentarem el nostre projecte\u2026.. Sembla que alguns han caminat molt i\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026..no estan gaire acostumats \u2026..uuuhhhhmmmmm!!!!!!<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-996","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}