{"id":999,"date":"2024-03-03T18:03:41","date_gmt":"2024-03-03T16:03:41","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/03\/visita-a-lescola-massana-centre-dart-i-disseny\/"},"modified":"2024-03-03T18:03:41","modified_gmt":"2024-03-03T16:03:41","slug":"visita-a-lescola-massana-centre-dart-i-disseny","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/2024\/03\/03\/visita-a-lescola-massana-centre-dart-i-disseny\/","title":{"rendered":"Visita a l\u2019Escola Massana. Centre d\u2019Art i Disseny."},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/visita-a-lescola-massana-centre-dart-i-disseny\/\">Mariona Ca\u00f1adas i Pedro Mur\u00faa EN RESiD\u00c8NCiA a l&#8217;Institut Escola El Mol\u00ed<\/a><\/p>\n<div>\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"623\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana2-1-1024x623.jpg\" alt=\"\" class=\"wp-image-862\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana2-1-1024x623.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana2-1-300x183.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana2-1-768x467.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana2-1.jpg 1060w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"690\" data-id=\"856\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana1-1024x690.jpg\" alt=\"\" class=\"wp-image-856\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana1-1024x690.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana1-300x202.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana1-768x517.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana1.jpg 1042w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" data-id=\"859\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana4-1024x686.jpg\" alt=\"\" class=\"wp-image-859\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana4-1024x686.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana4-300x201.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana4-768x514.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana4.jpg 1036w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"823\" height=\"691\" data-id=\"854\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana5.jpg\" alt=\"\" class=\"wp-image-854\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana5.jpg 823w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana5-300x252.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana5-768x645.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"698\" data-id=\"858\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana3-1024x698.jpg\" alt=\"\" class=\"wp-image-858\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana3-1024x698.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana3-300x204.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana3-768x523.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana3.jpg 1026w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"693\" data-id=\"860\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana6.jpg\" alt=\"\" class=\"wp-image-860\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana6.jpg 990w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana6-300x210.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana6-768x538.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"694\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana7-1.jpg\" alt=\"\" class=\"wp-image-863\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana7-1.jpg 930w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana7-1-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana7-1-768x573.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1018\" height=\"645\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana8.jpg\" alt=\"\" class=\"wp-image-861\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana8.jpg 1018w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana8-300x190.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/massana8-768x487.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Mariona Ca\u00f1adas i Pedro Mur\u00faa EN RESiD\u00c8NCiA a l&#8217;Institut Escola El Mol\u00ed<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-999","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/comments?post=999"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/posts\/999\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/media?parent=999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/categories?post=999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20232024\/wp-json\/wp\/v2\/tags?post=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}