{"id":1638,"date":"2025-02-09T21:06:56","date_gmt":"2025-02-09T19:06:56","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/2025\/02\/09\/evolucio-continua\/"},"modified":"2025-02-09T21:06:56","modified_gmt":"2025-02-09T19:06:56","slug":"evolucio-continua","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/2025\/02\/09\/evolucio-continua\/","title":{"rendered":"Evoluci\u00f3 cont\u00ednua"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/bastida2025\/evolucio-continua\/\">Toni Mira EN RESiD\u00c8NCiA a l\u2019Institut La Bastida<\/a><\/p>\n<div>L\u2019alumnat continua amb els assajos per a la mostra del pr\u00f2xim 19 de febrer, treballant intensament amb Toni Mira per perfilar cada detall de la presentaci\u00f3. A mesura que s\u2019apropa el dia, es concentren en la precisi\u00f3 del moviment, la connexi\u00f3 amb la m\u00fasica i l\u2019expressi\u00f3 corporal per transmetre tot el que han apr\u00e8s durant \u2026 <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/bastida2025\/evolucio-continua\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abEvoluci\u00f3 cont\u00ednua\u00bb<\/span><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Toni Mira EN RESiD\u00c8NCiA a l\u2019Institut La Bastida L\u2019alumnat continua amb els assajos per a la mostra del pr\u00f2xim 19 de febrer, treballant intensament amb Toni Mira per perfilar cada detall de la presentaci\u00f3. A mesura que s\u2019apropa el dia, es concentren en la precisi\u00f3 del moviment, la connexi\u00f3 amb la m\u00fasica i &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20242025\/2025\/02\/09\/evolucio-continua\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abEvoluci\u00f3 cont\u00ednua\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1638","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/posts\/1638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/comments?post=1638"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/posts\/1638\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/media?parent=1638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/categories?post=1638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/tags?post=1638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}