{"id":1736,"date":"2025-05-09T12:05:06","date_gmt":"2025-05-09T10:05:06","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/2025\/05\/09\/sesion-23-19-03-2025\/"},"modified":"2025-05-09T12:05:06","modified_gmt":"2025-05-09T10:05:06","slug":"sesion-23-19-03-2025","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/2025\/05\/09\/sesion-23-19-03-2025\/","title":{"rendered":"SESI\u00d3N 23 \u2013 19\/03\/2025"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2025\/sesion-23-19-03-2025\/\">Las Cosas EN RESiD\u00c8NCiA a l\u2019Institut Narc\u00eds Monturiol<\/a><\/p>\n<div>Ch\u00e3oc\u00e9u Esta sesi\u00f3n la dedicamos a hacer una excursi\u00f3n a la Caldera, un espacio de investigaci\u00f3n y de creaci\u00f3n de piezas art\u00edsticas relacionadas con danza y la expresi\u00f3n corporal. Salimos del instituto a las 10:15 h y cogimos el metro desde Montbau hasta las Corts (l\u00ednea verde). Llegamos a la localizaci\u00f3n unos minutos antes para \u2026 <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2025\/sesion-23-19-03-2025\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSESI\u00d3N 23 \u2013 19\/03\/2025\u00bb<\/span><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Las Cosas EN RESiD\u00c8NCiA a l\u2019Institut Narc\u00eds Monturiol Ch\u00e3oc\u00e9u Esta sesi\u00f3n la dedicamos a hacer una excursi\u00f3n a la Caldera, un espacio de investigaci\u00f3n y de creaci\u00f3n de piezas art\u00edsticas relacionadas con danza y la expresi\u00f3n corporal. Salimos del instituto a las 10:15 h y cogimos el metro desde Montbau hasta las Corts &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20242025\/2025\/05\/09\/sesion-23-19-03-2025\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSESI\u00d3N 23 \u2013 19\/03\/2025\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1736","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/posts\/1736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/comments?post=1736"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/posts\/1736\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/media?parent=1736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/categories?post=1736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20242025\/wp-json\/wp\/v2\/tags?post=1736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}