{"id":1535,"date":"2025-11-25T00:20:22","date_gmt":"2025-11-24T22:20:22","guid":{"rendered":"\/20252026\/dos-sesiones-con-luis\/"},"modified":"2025-11-25T00:20:22","modified_gmt":"2025-11-24T22:20:22","slug":"dos-sesiones-con-luis","status":"publish","type":"post","link":"\/20252026\/dos-sesiones-con-luis\/","title":{"rendered":"Dos sesiones con Luis"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/sants2026\/dos-sesiones-con-luis\/\">Carolina Torres Topaga EN RESiD\u00c8NCiA a l\u2019Institut Sants (Barcelona)<\/a><\/p>\n<div>\u201cEstuvimos dos sesiones con Luis, el sustituto de Carolina, debido a que durante dos semanas se tuvo que ir por trabajo. 1\u00aa sesi\u00f3n:Estuvimos bailando Tarantela Napolitana y reiniciamos la actividad de cada gesto por cada nombre,movernos por el escenario con m\u00fasica y cuando Luis aplaud\u00eda hac\u00edamos un movimiento que nos hab\u00eda ense\u00f1ado previamente y por \u2026 <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/sants2026\/dos-sesiones-con-luis\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abDos sesiones con Luis\u00bb<\/span><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Carolina Torres Topaga EN RESiD\u00c8NCiA a l\u2019Institut Sants (Barcelona) \u201cEstuvimos dos sesiones con Luis, el sustituto de Carolina, debido a que durante dos semanas se tuvo que ir por trabajo. 1\u00aa sesi\u00f3n:Estuvimos bailando Tarantela Napolitana y reiniciamos la actividad de cada gesto por cada nombre,movernos por el escenario con m\u00fasica y cuando Luis &hellip; <\/p>\n<p class=\"link-more\"><a href=\"\/20252026\/dos-sesiones-con-luis\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abDos sesiones con Luis\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"\/20252026\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/20252026\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/20252026\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/20252026\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"\/20252026\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":0,"href":"\/20252026\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"wp:attachment":[{"href":"\/20252026\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/20252026\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"\/20252026\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}