{"id":211,"date":"2022-12-20T13:13:55","date_gmt":"2022-12-20T11:13:55","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2022\/12\/20\/3-sesion-11-de-octubre\/"},"modified":"2022-12-20T13:13:55","modified_gmt":"2022-12-20T11:13:55","slug":"3-sesion-11-de-octubre","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2022\/12\/20\/3-sesion-11-de-octubre\/","title":{"rendered":"3. SESI\u00d3N. 11 de OCTUBRE"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/martipous2023\/2022\/12\/20\/3-sesion-11-de-octubre\/\">Gatillo Cul\u00f3n EN RESiD\u00c8NCiA<\/a><\/p>\n<div>\n<p>OBJETIVO: ANALIZAR UN ESPECT\u00c1CULO\/IMAGEN DEL CIRCO<\/p>\n<p>Empezamos la sesi\u00f3n en circulo recordando los nombres. Explicamos que con los referentes de la semana pasada se va a hacer una carpeta en Pinterest con todos ellos y algunos m\u00e1s relacionados con ellos, para entender como de una imagen podemos ahondar y encontrar muchas m\u00e1s cosas que nos puedan ayudar a generar una idea m\u00e1s amplia de los temas o los conceptos que nos gustan. Algo importante que queremos expresarles es que cuando se pidamos tareas de traer material audiovisual, tienen que ser cosas que no les de verg\u00fcenza que las otras personas conozcan de vosotros.<\/p>\n<p>En clase  debemos escoger una p\u00e1gina que nos guste mucho de Instagram y las veremos todas aqu\u00ed.  Compartimos entre todos algunos ejemplos @beurkmagazine. A partir de ahora, cada alumno\/a cuelga en classroom  sus referentes. <\/p>\n<p>A continuaci\u00f3n trabajamos sobre cuadro de la historia del arte, de la \u00e9poca que se escoja, se les recomienda \u00e9pocas del renacimiento o del barroco. Porque hemos elegido ese cuadro?<\/p>\n<p>Ejemplo: \u201cDescendimiento de la cruz (Rogier van der Weyden)\u201d. Me gusta por el drama que tienen los cuerpos, las espresiones de la cara y como todos los cuerpos caen hacia abajo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Gatillo Cul\u00f3n EN RESiD\u00c8NCiA OBJETIVO: ANALIZAR UN ESPECT\u00c1CULO\/IMAGEN DEL CIRCO Empezamos la sesi\u00f3n en circulo recordando los nombres. Explicamos que con los referentes de la semana pasada se va a hacer una carpeta en Pinterest con todos ellos y algunos m\u00e1s relacionados con ellos, para entender como de una imagen podemos ahondar y &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2022\/12\/20\/3-sesion-11-de-octubre\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00ab3. SESI\u00d3N. 11 de OCTUBRE\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-211","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/211\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/categories?post=211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}