{"id":245,"date":"2023-01-24T19:24:37","date_gmt":"2023-01-24T17:24:37","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/01\/24\/nadal-a-tocar\/"},"modified":"2023-01-24T19:24:37","modified_gmt":"2023-01-24T17:24:37","slug":"nadal-a-tocar","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/01\/24\/nadal-a-tocar\/","title":{"rendered":"Nadal a tocar\u2026"},"content":{"rendered":"<p>Des de <a href=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/2023\/01\/24\/nadal-a-tocar\/\">Oriol Puig Grau EN RESiD\u00c8NCiA<\/a><\/p>\n<div>\n<p>S\u2019apropa Nadal, s\u2019ensumen les vacances a l\u2019ambient i avui l\u2019Oriol decideix fer una sessi\u00f3 de relaxaci\u00f3, inmersi\u00f3 en un m\u00f3n intim i personal, provocat per la tranquilitat i una m\u00fasica envolvent i sugerent.<\/p>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Relajaci\u00f3n: M\u00fasica para Relajarse y Calmar la Mente - M\u00fasica de la Naturaleza\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/DNrnDx-KZUY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div>\n<\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0797-1024x768.jpg\" alt=\"\" class=\"wp-image-58\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0797-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0797-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0797-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0797-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0797-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0798-1024x768.jpg\" alt=\"\" class=\"wp-image-59\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0798-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0798-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0798-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0798-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0798-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0847-768x1024.jpg\" alt=\"\" class=\"wp-image-60\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0847-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0847-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0847-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0847-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0847-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0848-768x1024.jpg\" alt=\"\" class=\"wp-image-61\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0848-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0848-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0848-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0848-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0848-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0849-768x1024.jpg\" alt=\"\" class=\"wp-image-62\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0849-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0849-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0849-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0849-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0849-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<p>Un cop fet\u2026 rentabilitzem la proposta amb un exercici d\u2019escriptura autom\u00e0tica de conceptes, idees i sensacions, sense pensar, de forma intu\u00eftiva\u2026 el resultat, tota una s\u00e8rie de declaracions vitals molt punyents que constituiran el punt de partida del nostre text dram\u00e0tic.<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0850-768x1024.jpg\" alt=\"\" class=\"wp-image-63\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0850-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0850-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0850-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0850-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0850-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0851-768x1024.jpg\" alt=\"\" class=\"wp-image-64\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0851-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0851-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0851-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0851-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0851-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0853-768x1024.jpg\" alt=\"\" class=\"wp-image-65\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0853-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0853-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0853-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0853-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0853-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<p>I ara, ens toca gaudir d\u2019unes magn\u00edfiques festes! Apa, Bon Nadal a tothom!<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0802-768x1024.jpg\" alt=\"\" class=\"wp-image-66\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0802-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0802-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0802-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0802-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/barribesos2023\/wp-content\/uploads\/2023\/01\/IMG_0802-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\"><\/figure>\n<p>Jordi S\u00e1nchez.<\/p>\n<p>Professor.<\/p>\n<p>Institut Barri Bes\u00f2s.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des de Oriol Puig Grau EN RESiD\u00c8NCiA S\u2019apropa Nadal, s\u2019ensumen les vacances a l\u2019ambient i avui l\u2019Oriol decideix fer una sessi\u00f3 de relaxaci\u00f3, inmersi\u00f3 en un m\u00f3n intim i personal, provocat per la tranquilitat i una m\u00fasica envolvent i sugerent. Un cop fet\u2026 rentabilitzem la proposta amb un exercici d\u2019escriptura autom\u00e0tica de conceptes, idees i &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/20222023\/2023\/01\/24\/nadal-a-tocar\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abNadal a tocar\u2026\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-245","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":0,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/posts\/245\/revisions"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/media?parent=245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/categories?post=245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/20222023\/wp-json\/wp\/v2\/tags?post=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}