{"id":125,"date":"2023-03-07T16:52:23","date_gmt":"2023-03-07T14:52:23","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/?p=125"},"modified":"2023-03-07T16:52:23","modified_gmt":"2023-03-07T14:52:23","slug":"videos-rompetusmales-i-contaminacio","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/2023\/03\/07\/videos-rompetusmales-i-contaminacio\/","title":{"rendered":"V\u00eddeos #RompeTusMales i Contaminaci\u00f3"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color\"><strong>Shakra<\/strong> &#8220;Un cop la performance va tenir lloc, i un cop el nostre objectiu es va complir, ja era hora d\u2019editar els v\u00eddeos que vam gravar durant l\u2019esdeveniment.\u00a0<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">En aquest, a trav\u00e9s de l\u2019acci\u00f3 de trencar els calendaris gegants que vam crear durant les sessions anteriors, ens vam acabar reivindicant. Aquesta manera d\u2019expressar-nos no la ten\u00edem prevista, per\u00f2 va acabar sent una molt bona idea, alegre i divertida, per a alliberar aquests malestars que ten\u00edem.&#8221;.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/Avorriment_editado.mp4\"><\/video><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/video_julio_tranquilidad.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color\">&#8220;A continuaci\u00f3, tota aquesta experi\u00e8ncia viscuda durant el projecte la vam voler compartir amb el professorat de 4t d\u2019ESO, i aix\u00ed va ser. Per fer-ho, ens vam organitzar en quatre grups i cadascun tenia la responsabilitat d\u2019explicar alguna determinada part del proc\u00e9s.&#8221;.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_142830-1024x768.jpg\" alt=\"\" class=\"wp-image-130\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_142830-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_142830-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_142830-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_142830-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_142830-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/CREADORS-EN-RESIDENCIA-2.pdf\" type=\"application\/pdf\" style=\"width:100%;height:500px\" aria-label=\"Incrustaci\u00f3 del fitxer Una de les presentacions compartides amb el professorat de 4t d&#039;ESO.\"><\/object><a id=\"wp-block-file--media-f922fa7a-42ee-4b02-a499-11f92797376d\" href=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/CREADORS-EN-RESIDENCIA-2.pdf\">Una de les presentacions compartides amb el professorat de 4t d&#8217;ESO<\/a><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389280997_121-1024x768.jpg\" alt=\"\" class=\"wp-image-140\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389280997_121-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389280997_121-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389280997_121-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389280997_121.jpg 1280w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281000_121-1024x768.jpg\" alt=\"\" class=\"wp-image-141\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281000_121-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281000_121-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281000_121-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281000_121.jpg 1280w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG-20230201-WA0037-771x1024.jpg\" alt=\"\" class=\"wp-image-142\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG-20230201-WA0037-771x1024.jpg 771w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG-20230201-WA0037-226x300.jpg 226w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG-20230201-WA0037-768x1021.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG-20230201-WA0037-1156x1536.jpg 1156w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG-20230201-WA0037.jpg 1204w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281003_121-1024x768.jpg\" alt=\"\" class=\"wp-image-143\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281003_121-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281003_121-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281003_121-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281003_121.jpg 1280w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_171626_1-1024x768.jpg\" alt=\"\" class=\"wp-image-144\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_171626_1-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_171626_1-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_171626_1-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_171626_1-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/IMG_20230201_171626_1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281004_121-1024x768.jpg\" alt=\"\" class=\"wp-image-145\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281004_121-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281004_121-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281004_121-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281004_121.jpg 1280w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281005_121-1024x768.jpg\" alt=\"\" class=\"wp-image-146\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281005_121-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281005_121-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281005_121-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/02\/5972023975389281005_121.jpg 1280w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Durant la sessi\u00f3 de contaminaci\u00f3 l&#8217;alumnat va proposar a l&#8217;equip docent una acci\u00f3 de participaci\u00f3: escriure preocupacions, sentiments, malestars que viuen en relaci\u00f3 amb el temps a l&#8217;institut, i despr\u00e9s enganxar els postits en els mesos de juny i juliol.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/03\/5972023975389281009_121-1-1024x768.jpg\" alt=\"\" class=\"wp-image-148\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/03\/5972023975389281009_121-1-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/03\/5972023975389281009_121-1-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/03\/5972023975389281009_121-1-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-content\/uploads\/2023\/03\/5972023975389281009_121-1.jpg 1280w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>A la setmana seg\u00fcent, a l&#8217;aula, es va reflexionar sobre com una part de la comunitat (alumnes i docents) que habita l&#8217;institut, pot arribar a compartir algunes de les mateixes preocupacions, sentiments, malestars que es viuen. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shakra &#8220;Un cop la performance va tenir lloc, i un cop el nostre objectiu es va complir, ja era hora d\u2019editar els v\u00eddeos que vam gravar durant l\u2019esdeveniment.\u00a0 En aquest, a trav\u00e9s de l\u2019acci\u00f3 de trencar els calendaris gegants que vam crear durant les sessions anteriors, ens vam acabar reivindicant. Aquesta manera d\u2019expressar-nos no la &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/2023\/03\/07\/videos-rompetusmales-i-contaminacio\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abV\u00eddeos #RompeTusMales i Contaminaci\u00f3\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-125","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/posts\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":13,"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/posts\/125\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/posts\/125\/revisions\/152"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/media?parent=125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/categories?post=125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/conselldecent2023\/wp-json\/wp\/v2\/tags?post=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}