{"id":58,"date":"2022-12-12T13:28:04","date_gmt":"2022-12-12T11:28:04","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/?p=58"},"modified":"2023-01-11T17:51:39","modified_gmt":"2023-01-11T15:51:39","slug":"moguem-nos","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/2022\/12\/12\/moguem-nos\/","title":{"rendered":"Moguem-nos"},"content":{"rendered":"\n<p>La sessi\u00f3 d\u2019avu\u00ed l\u2019hem dividit en dues parts:<\/p>\n\n\n\n<p>1a Hem iniciat la llibreta d\u2019artista.<\/p>\n\n\n\n<p>2a Hem fet una activitat que tracta sobre com ens posicionem en l\u2019espai.<\/p>\n\n\n\n<p>A la classe d&#8217;avui ens hem dividit en grups. Aquest grup est\u00e0 tallant les cartolines de colors variats per fer la folra de les llibretes d\u2019artista. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"451\" height=\"338\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-13.png\" alt=\"\" class=\"wp-image-59\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-13.png 451w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-13-300x225.png 300w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"358\" height=\"269\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-14.png\" alt=\"\" class=\"wp-image-60\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-14.png 358w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-14-300x225.png 300w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"463\" height=\"310\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-15.png\" alt=\"\" class=\"wp-image-61\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-15.png 463w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-15-300x201.png 300w\" sizes=\"auto, (max-width: 463px) 100vw, 463px\" \/><\/figure>\n\n\n\n<p>Aquest grup ha estat retallant les tapes dures de la llibreta d\u2019artista.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"978\" height=\"734\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-16.png\" alt=\"\" class=\"wp-image-62\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-16.png 978w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-16-300x225.png 300w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-16-768x576.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Aquest grup estan enganxant les tapes dures i les cartolines de la part de dintre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"851\" height=\"639\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-17.png\" alt=\"\" class=\"wp-image-63\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-17.png 851w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-17-300x225.png 300w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-17-768x577.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Hi ha hagut un grup que a estat enganxant la cartulina amb les tapes dures<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"781\" height=\"586\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-18.png\" alt=\"\" class=\"wp-image-64\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-18.png 781w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-18-300x225.png 300w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-18-768x576.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Activitat: com ens posicionem a l\u2019espai: <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"529\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-21.png\" alt=\"\" class=\"wp-image-67\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-21.png 705w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-21-300x225.png 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n\n\n\n<p>Ens posicionem a l&#8217;espai de forma grupal.<\/p>\n\n\n\n<p>Aquesta activitat ha consistit en posar-se en una postura en la relaci\u00f3 als altres. Tots haviem d\u2019estar en contacte com a m\u00ednim amb un company.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"997\" height=\"748\" src=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-22.png\" alt=\"\" class=\"wp-image-68\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-22.png 997w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-22-300x225.png 300w, https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-content\/uploads\/2022\/12\/image-22-768x576.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Berta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sessi\u00f3 d\u2019avu\u00ed l\u2019hem dividit en dues parts: 1a Hem iniciat la llibreta d\u2019artista. 2a Hem fet una activitat que tracta sobre com ens posicionem en l\u2019espai. A la classe d&#8217;avui ens hem dividit en grups. Aquest grup est\u00e0 tallant les cartolines de colors variats per fer la folra de les llibretes d\u2019artista. Aquest grup &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/2022\/12\/12\/moguem-nos\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abMoguem-nos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/posts\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":2,"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/posts\/58\/revisions"}],"predecessor-version":[{"id":71,"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/posts\/58\/revisions\/71"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/media?parent=58"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/categories?post=58"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/eljoncar2023\/wp-json\/wp\/v2\/tags?post=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}