{"id":232,"date":"2023-05-18T10:47:40","date_gmt":"2023-05-18T08:47:40","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/?p=232"},"modified":"2023-05-18T10:50:20","modified_gmt":"2023-05-18T08:50:20","slug":"els-jocs-de-taula","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/2023\/05\/18\/els-jocs-de-taula\/","title":{"rendered":"Els jocs de taula"},"content":{"rendered":"\n<p>En les \u00faltimes sessions vam coincidir que la millor manera per reunir-se amb gent i una de les maneres m\u00e9s properes, era a partir de jocs de taula o cartes. Per aix\u00f2, i entre tots vam fer una llista de llocs que solem utilitzar i jugar quan estem en grup. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230316121814-1024x768.jpg\" alt=\"\" class=\"wp-image-233\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230316121814-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230316121814-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230316121814-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230316121814-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230316121814-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>A partir de posar-ho en com\u00fa, per grups, vam decidir quins jocs ens agradaria tunejar. Havia de ser un joc que faci pensar, posant de manifest les situacions d\u2019aquelles persones immigrants, gent gran o qualsevol col\u00b7lectiu en risc d\u2019exclusi\u00f3. <\/p>\n\n\n\n<p>Vam dedicar dues sessions de jugar a aquests jocs i pensar de quina manera modificar-los o tunejar-los, amb les tem\u00e0tiques de treball: gent gran i persones immigrades. Ara els estem construint. Cada grup est\u00e0 fent el seu joc. Excepte un grup s\u2019encarrega de fer un carro per poder transportar tots els elements i els jocs, per generar espais de trobada a qualsevol espai. Ha de ser itinerant.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"242\" src=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103349-1-1024x768.jpg\" alt=\"\" class=\"wp-image-242\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103349-1-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103349-1-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103349-1-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103349-1-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103349-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"234\" src=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103341-768x1024.jpg\" alt=\"\" class=\"wp-image-234\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103341-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103341-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103341-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103341-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103341-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"241\" src=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103353-1-768x1024.jpg\" alt=\"\" class=\"wp-image-241\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103353-1-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103353-1-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103353-1-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103353-1-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103353-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"245\" src=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103411-1-1024x768.jpg\" alt=\"\" class=\"wp-image-245\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103411-1-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103411-1-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103411-1-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103411-1-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103411-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"244\" src=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103403_01-2-1024x768.jpg\" alt=\"\" class=\"wp-image-244\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103403_01-2-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103403_01-2-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103403_01-2-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103403_01-2-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-content\/uploads\/2023\/05\/IMG20230323103403_01-2-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En les \u00faltimes sessions vam coincidir que la millor manera per reunir-se amb gent i una de les maneres m\u00e9s properes, era a partir de jocs de taula o cartes. Per aix\u00f2, i entre tots vam fer una llista de llocs que solem utilitzar i jugar quan estem en grup. A partir de posar-ho en &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/2023\/05\/18\/els-jocs-de-taula\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abEls jocs de taula\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-232","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":3,"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"predecessor-version":[{"id":249,"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/posts\/232\/revisions\/249"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/joanbrossa2023\/wp-json\/wp\/v2\/tags?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}