{"id":317,"date":"2023-11-30T11:30:41","date_gmt":"2023-11-30T09:30:41","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/?p=317"},"modified":"2023-11-30T11:30:41","modified_gmt":"2023-11-30T09:30:41","slug":"sesion-4-18-10-23","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/sesion-4-18-10-23\/","title":{"rendered":"Sesi\u00f3n 4 &#8211; 18\/10\/23"},"content":{"rendered":"\n<p>Para esta sesi\u00f3n tuvimos que perder la hora de patio, ya que salimos a las once. Esto lo tuvimos que hacer porque Sara ten\u00eda una reuni\u00f3n y ten\u00edamos que estar ah\u00ed a las once y media. Para compensarlo nos dejaron tiempo libre hasta las once y cincuenta. <br><\/p>\n\n\n\n<p>Al empezar la clase, Lautaro nos hizo una pregunta:  \u201c\u00bfQu\u00e9 os gusta hacer?\u201d. Parece una pregunta sencilla, pero estuvimos un rato pensando y escribi\u00e9ndolo. La dificultad estaba en que ten\u00edamos que argumentarlo y despu\u00e9s sintetizarlo en un concepto.<\/p>\n\n\n\n<p><br>Luego, volvimos a retomar los ejercicios corporales. Lautaro nos separ\u00f3 en tr\u00edos y en parejas y tuvimos que mantener el equilibrio agarr\u00e1ndonos de la mano. Al principio nos cost\u00f3, pero al final lo conseguimos. Entonces, fuimos ampliando los grupos hasta conseguir dos grupos grandes. Esta vez ten\u00edamos unas consignas que seguir: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Agarrarnos de los compa\u00f1eros de los brazos u hombros. <\/li>\n\n\n\n<li>2. Movilizar la composici\u00f3n, buscar contrapesos. <\/li>\n\n\n\n<li>3. Levantarnos de forma muy lenta. <\/li>\n<\/ul>\n\n\n\n<p>A continuaci\u00f3n, lo repetimos con m\u00fasica. <\/p>\n\n\n\n<p>Al acabar, a\u00f1adi\u00f3 una nueva consiga que era sospetener al compa\u00f1ero solamente con una mano (la otra ten\u00eda que quedar libre). Nos dijo que as\u00ed se implementaba la estabilidad de nuestro cuerpo.<\/p>\n\n\n\n<p><br>Aunque la sesi\u00f3n se hizo larga para algunos, esta tuvo dinamismo porque las figuras ten\u00edan m\u00e1s movimientos. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"338\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_130143-1024x766.jpg\" alt=\"\" class=\"wp-image-338\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_130143-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_130143-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_130143-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_130143-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_130143-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1916\" data-id=\"336\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122902-2-scaled.jpg\" alt=\"\" class=\"wp-image-336\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122902-2-scaled.jpg 2560w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122902-2-300x225.jpg 300w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"337\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122829-1024x766.jpg\" alt=\"\" class=\"wp-image-337\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122829-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122829-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122829-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122829-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122829-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" data-id=\"335\" src=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122833-3-1024x766.jpg\" alt=\"\" class=\"wp-image-335\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122833-3-1024x766.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122833-3-300x224.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122833-3-768x575.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122833-3-1536x1149.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-content\/uploads\/2023\/11\/IMG_20231018_122833-3-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Para esta sesi\u00f3n tuvimos que perder la hora de patio, ya que salimos a las once. Esto lo tuvimos que hacer porque Sara ten\u00eda una reuni\u00f3n y ten\u00edamos que estar ah\u00ed a las once y media. Para compensarlo nos dejaron tiempo libre hasta las once y cincuenta. Al empezar la clase, Lautaro nos hizo una &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/sesion-4-18-10-23\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abSesi\u00f3n 4 &#8211; 18\/10\/23\u00bb<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-317","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/posts\/317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/comments?post=317"}],"version-history":[{"count":4,"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/posts\/317\/revisions"}],"predecessor-version":[{"id":383,"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/posts\/317\/revisions\/383"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/categories?post=317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/narcismonturiol2024\/wp-json\/wp\/v2\/tags?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}