{"id":299,"date":"2023-11-19T20:58:14","date_gmt":"2023-11-19T18:58:14","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/?p=299"},"modified":"2023-11-19T20:58:14","modified_gmt":"2023-11-19T18:58:14","slug":"comencem-visitant-lexposicio-un-album-familiar-de-cures","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/comencem-visitant-lexposicio-un-album-familiar-de-cures\/","title":{"rendered":"Comencem visitant l&#8217;exposici\u00f3 &#8220;Un \u00e0lbum familiar de cures&#8221;"},"content":{"rendered":"\n<p>Aquest curs a l&#8217;institut La Sagrera Sant Andreu vam comen\u00e7ar l\u2019assignatura d\u2019art que tantes ganes tenia de fer. Resulta que aquest any, igual que el curs passat, participem del programa Creadors en Resid\u00e8ncia. En aquell moment no sabia ben b\u00e9 de qu\u00e8 anava l\u2019assignatura, per\u00f2 ara ja comencem a entendre-ho. <br>Despr\u00e9s de con\u00e8ixer l\u2019artista convidada, al nostre cas, la Tatiana Donoso, de fer unes sessions amb ella i mostrar-nos com treballa, comencem a veure de qu\u00e8 est tracta. Ella \u00e9s una fot\u00f2grafa que fa servir altres t\u00e8cniques que combina amb la fotografia.<br>A la segona setmana de comen\u00e7ar, a l&#8217;octubre, vam anar a veure l\u2019exposici\u00f3 \u201cUn \u00e0lbum familiar de cures\u201d estava formada per unes fotografies de situacions quotidianes de l&#8217;\u00e0mbit dom\u00e8stic, impreses o brodades en draps de cuina. Totes les imatges estaven acompanyades amb tiquets de la compra amb el temps que es triga a realitzar les accions de les respectives fotografies i l\u2019esfor\u00e7 que aquestes suposen. Tamb\u00e9 hi havia un banc amb fanzines fets pel grup d\u2019alumnes que aquesta artista va acompanyar l\u2019any anterior on els van proposar el seu propi \u00e0lbum de cures a les seves cases.<br>Despr\u00e9s vam poder escollir entre alguns dels tiquets de cures que hi havia a sobre d&#8217;una taula vam fer un petit \u201cdebat\u201d explicant la nostra elecci\u00f3. <br>A gran part dels alumnes els hi va semblar que les imatges eren molt simples i que qualsevol persona els hagu\u00e9s pogut fer. Uns altres podien empatitzar millor amb aquestes, i valorar-la d\u2019una manera m\u00e9s profunda. Tamb\u00e9 n&#8217;hi havia alguns que no sabien posicionar-se. <br>El que l\u2019artista volia expressar era el fet que a casa s\u2019han de fer un munt de tasques que no es veuen socialment, ja que es consideren coses \u00edntimes que no passen d\u2019un context aix\u00ed. Que, desgraciadament, per molt esfor\u00e7 i temps que hi dediquem continuaran sent invisibles i no ens seran retribu\u00efdes econ\u00f2micament.<br><br>Laia Bayo (4t ESO)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874434-1-1024x555.jpg\" alt=\"\" class=\"wp-image-309\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874434-1-1024x555.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874434-1-300x163.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874434-1-768x416.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874434-1-1536x832.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874434-1-2048x1110.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"774\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874394-1024x774.jpg\" alt=\"\" class=\"wp-image-308\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874394-1024x774.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874394-300x227.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874394-768x581.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874394-1536x1162.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874394-2048x1549.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"604\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874099-1-1024x604.jpg\" alt=\"\" class=\"wp-image-307\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874099-1-1024x604.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874099-1-300x177.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874099-1-768x453.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874099-1-1536x906.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874099-1-2048x1208.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874192-1024x768.jpg\" alt=\"\" class=\"wp-image-310\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874192-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874192-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874192-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-content\/uploads\/2023\/11\/1698926874192.jpg 1232w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Aquest curs a l&#8217;institut La Sagrera Sant Andreu vam comen\u00e7ar l\u2019assignatura d\u2019art que tantes ganes tenia de fer. Resulta que aquest any, igual que el curs passat, participem del programa Creadors en Resid\u00e8ncia. En aquell moment no sabia ben b\u00e9 de qu\u00e8 anava l\u2019assignatura, per\u00f2 ara ja comencem a entendre-ho. Despr\u00e9s de con\u00e8ixer l\u2019artista convidada, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/comencem-visitant-lexposicio-un-album-familiar-de-cures\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abComencem visitant l&#8217;exposici\u00f3 &#8220;Un \u00e0lbum familiar de cures&#8221;\u00bb<\/span><\/a><\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-299","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/posts\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":3,"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/posts\/299\/revisions"}],"predecessor-version":[{"id":313,"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/posts\/299\/revisions\/313"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/media?parent=299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/categories?post=299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sagrerasantandreu2024\/wp-json\/wp\/v2\/tags?post=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}