{"id":59,"date":"2022-12-01T12:31:03","date_gmt":"2022-12-01T10:31:03","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/?p=59"},"modified":"2022-12-12T14:07:33","modified_gmt":"2022-12-12T12:07:33","slug":"quienes-somos","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/2022\/12\/01\/quienes-somos\/","title":{"rendered":"\u00bfQui\u00e9nes somos?"},"content":{"rendered":"\n<p class=\"has-text-align-left\">\u201cHola, me llamo <strong>Niharika<\/strong> y soy de Nepal, aunque vine a Espa\u00f1a hace cuatro a\u00f1os. Tengo 13 a\u00f1os y voy al Instituto Sants. Tengo un hermano. Me gusta bailar y escuchar m\u00fasica y tambi\u00e9n comer y dormir. Soy una persona introvertida y un poco callada, pero no me callo cuando estoy con personas con las que tengo confianza. Me gustan los perros y los gatos. De mayor, me gustar\u00eda ser doctora.\u201d<\/p>\n\n\n\n<p class=\"has-text-align-left\">\u201cHola, me llamo <strong>Natalia <\/strong>y tengo 12 a\u00f1os. Soy de Polonia, pero vivo en Espa\u00f1a desde segundo de primaria y voy al Institut Sants. Me gusta pasar tiempo con mis amigos, mi deporte favorito es el balonmano y lo practico desde hace casi 5 a\u00f1os. Me hace ilusi\u00f3n participar en este proyecto solo que creo que me ser\u00e1 dif\u00edcil hacerlo porque yo de artista tengo poco.\u201d<\/p>\n\n\n\n<p class=\"has-text-align-left\">\u201cMe llamo\u00a0<strong>Aurora <\/strong>Villoro, tengo 13 a\u00f1os y he nacido en Barcelona. Ahora mismo estoy estudiando en el instituto Emperador Carles. Un d\u00eda nuestra tutora nos dijo que \u00edbamos a hacer un proyecto con una artista, P\u00eda. Desde ese momento he estado muy ilusionada con el proyecto. Nos ha ense\u00f1ado a hacer \u201cfrottage\u201d, una t\u00e9cnica\u00a0para grabar la textura del suelo y espero que nos ense\u00f1e muchas m\u00e1s&#8230; Un saludo.\u201d<\/p>\n\n\n\n<p>&#8220;Me llamo <strong>Amy<\/strong> y tengo trece a\u00f1os. Lo que m\u00e1s me gusta es bailar, y estar con mis amigas  , amigos y familiares. Hacer re\u00edr a la gente se me da bastante bien igual que re\u00edr, ya que me r\u00edo por todo. El proyecto est\u00e1 siendo bastante divertido y entretenido, sobre todo el frottage, que es de mis cosas favoritas como tambi\u00e9n la grabadora , ya que es curioso como se escuha todo\u00a0&#8220;.<\/p>\n\n\n\n<p class=\"has-text-align-left\">\u201cHola me llamo <strong>Charles Xavie<\/strong>r Mercado Pacis y tengo trece a\u00f1os. Tengo tres hermanos mucho m\u00e1s mayores que yo, as\u00ed que soy el m\u00e1s peque\u00f1o de mi familia. En mi tiempo libre la verdad es que no hago gran cosa, voy a jugar a b\u00e1squet. Mi comida favorita es el sissig(una comida filipina). Mi deporte favorito claramente es el b\u00e1squet, pero cuando era peque\u00f1o me gustaba m\u00e1s el f\u00fatbol, no s\u00e9 porque cambi\u00e9 tan radicalmente.\u201d<\/p>\n\n\n\n<p>\u201cMe llamo <strong>Gabriela<\/strong>, tengo 13 a\u00f1os soy de Cuba y llevo 2 a\u00f1os viviendo en Barcelona, me gusta bailar y a veces dibujar.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-content\/uploads\/2022\/12\/IMG_4006-1024x768.jpg\" alt=\"\" class=\"wp-image-64\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-content\/uploads\/2022\/12\/IMG_4006-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-content\/uploads\/2022\/12\/IMG_4006-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-content\/uploads\/2022\/12\/IMG_4006-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-content\/uploads\/2022\/12\/IMG_4006-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-content\/uploads\/2022\/12\/IMG_4006-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>&#8220;Hola, me llamo <strong>Randy<\/strong> y tengo trece a\u00f1os,. Nac\u00ed en Espa\u00f1a y mis padres son de Ecuador. Me gustan mucho los videojuegos y aprender experiencias nuevas. Este proyecto por ahora me est\u00e1 encantando porque aprendo cosas sobre el frottage y del escucha. Espero que siga siendo igual de interesante que ahora.&#8221;<\/p>\n\n\n\n<p>&#8220;Hola, me llamo <strong>Toqeer<\/strong>, tengo trece a\u00f1os y me gusta el b\u00e1squet. &#8220;<\/p>\n\n\n\n<p>&#8220;Hola, me llamo <strong>Chengjun<\/strong> y tengo trece a\u00f1os. Soy de China y mi deporte favorito es el b\u00e1squet&#8221;<\/p>\n\n\n\n<p>&#8220;Hola, me llamo <strong>Alison<\/strong> y tengo trece a\u00f1os . Voy al Instituto Sants y  mi curso es 2\u00baC. Hacemos un proyecto en castellano con el que vamos al Museo nacional de Catalunya y tambi\u00e9n  hacemos actividades en clase  con nuestra tutora y con P\u00eda, la artista del proyecto. Me est\u00e1 gustando  mucho y pienso que estamos haciendo un buen trabajo. &#8220;<\/p>\n\n\n\n<p>&#8220;Hola,me llamo <strong>Meriem<\/strong> ,tengo 14 a\u00f1os y nac\u00ed en Zaragoza  aunque soy de origen argelino. desde hace dos a\u00f1os estoy viviendo en Barcelona. Estudi\u00e9 en l&#8217;Escola Pr\u00e0ctiques y ahora estoy en el Institut S ants. <\/p>\n\n\n\n<p>Me gusta dibujar ,el baloncesto , hablar y re\u00edrme .He practicado todo tipo de deportes (patinaje,baloncesto,f\u00fatbol\u2026), pero lo que m\u00e1s me gusta es dibujar y en este proyecto de momento sigo sin encajar. &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cHola, me llamo Niharika y soy de Nepal, aunque vine a Espa\u00f1a hace cuatro a\u00f1os. Tengo 13 a\u00f1os y voy al Instituto Sants. Tengo un hermano. Me gusta bailar y escuchar m\u00fasica y tambi\u00e9n comer y dormir. Soy una persona introvertida y un poco callada, pero no me callo cuando estoy con personas con las &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/2022\/12\/01\/quienes-somos\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00ab\u00bfQui\u00e9nes somos?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-59","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/posts\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":4,"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/posts\/59\/revisions"}],"predecessor-version":[{"id":75,"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/posts\/59\/revisions\/75"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/media?parent=59"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/categories?post=59"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/sants2023\/wp-json\/wp\/v2\/tags?post=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}