{"id":290,"date":"2023-12-04T13:12:26","date_gmt":"2023-12-04T11:12:26","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/?p=290"},"modified":"2023-12-04T13:12:26","modified_gmt":"2023-12-04T11:12:26","slug":"el-primer-dia-que-coneixem-a-la-constanza","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/el-primer-dia-que-coneixem-a-la-constanza\/","title":{"rendered":"El primer dia que coneixem a la Constanza"},"content":{"rendered":"\n<p>La sessi\u00f3 ha estat molt especial!<\/p>\n\n\n\n<p>Hem conegut la Constanza Brncic, que \u00e9s ballarina i amb qui treballarem tot el curs. Est\u00e0vem tots  molt nerviosos i emocionats.<\/p>\n\n\n\n<p>Hem anat al Mercat de les Flors. Ens ha agradat molt i volem tornar.<\/p>\n\n\n\n<p>Hem ballat. I ens ha agradat. <\/p>\n\n\n\n<p>Hem vist la Constanza ballar i ens ha emocionat.<\/p>\n\n\n\n<p>Hem acabat el dia a Montjuic mirant Barcelona.<\/p>\n\n\n\n<p>Hem celebrat l&#8217;aniversari de la Constanza, cantant-li una can\u00e7\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"291\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_02-1024x768.jpg\" alt=\"\" class=\"wp-image-291\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_02-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_02-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_02-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_02-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_02-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"292\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_16-1024x768.jpg\" alt=\"\" class=\"wp-image-292\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_16-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_16-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_16-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_16-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_16-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"293\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_32-1024x768.jpg\" alt=\"\" class=\"wp-image-293\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_32-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_32-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_32-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_32-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_32-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"294\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_43-1024x768.jpg\" alt=\"\" class=\"wp-image-294\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_43-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_43-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_43-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_43-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_43-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"295\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_50-1024x768.jpg\" alt=\"\" class=\"wp-image-295\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_50-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_50-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_50-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_50-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_50-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"296\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_74-1024x768.jpg\" alt=\"\" class=\"wp-image-296\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_74-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_74-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_74-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_74-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_74-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"297\" src=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_83-1024x768.jpg\" alt=\"\" class=\"wp-image-297\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_83-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_83-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_83-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_83-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-content\/uploads\/2023\/12\/231006_MercatFlors_1asessio_83-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La sessi\u00f3 ha estat molt especial! Hem conegut la Constanza Brncic, que \u00e9s ballarina i amb qui treballarem tot el curs. Est\u00e0vem tots molt nerviosos i emocionats. Hem anat al Mercat de les Flors. Ens ha agradat molt i volem tornar. Hem ballat. I ens ha agradat. Hem vist la Constanza ballar i ens ha &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/el-primer-dia-que-coneixem-a-la-constanza\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abEl primer dia que coneixem a la Constanza\u00bb<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-290","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/posts\/290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/comments?post=290"}],"version-history":[{"count":2,"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/posts\/290\/revisions"}],"predecessor-version":[{"id":325,"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/posts\/290\/revisions\/325"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/media?parent=290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/categories?post=290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/turocaritg2024\/wp-json\/wp\/v2\/tags?post=290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}