{"id":302,"date":"2023-12-30T12:24:11","date_gmt":"2023-12-30T10:24:11","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/?p=302"},"modified":"2023-12-30T12:29:16","modified_gmt":"2023-12-30T10:29:16","slug":"todo-el-mundo-es-artistaaunque-no-lo-sepa-y-aunque-no-quiera","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/todo-el-mundo-es-artistaaunque-no-lo-sepa-y-aunque-no-quiera\/","title":{"rendered":"TOT EL M\u00d3N \u00c9S ARTISTA(ENCARA QUE NO HO S\u00c0PIGA I ENCARA QUE NO HO VULGUI)"},"content":{"rendered":"\n<p>Aquesta frase va ser la primera que vam con\u00e8ixer de l&#8217;Antonio Ortega quan la tutora ens va mostrar a classe el document que parlava d&#8217;ell &#8230;. ENS AGRADA AQUESTA IDEA!!!! Vol dir que nosaltres tamb\u00e9 ho som&#8230;?????<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2023\/12\/IMG_20230921_091658-1-768x1024.jpg\" alt=\"\" class=\"wp-image-306\" style=\"width:389px;height:auto\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2023\/12\/IMG_20230921_091658-1-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2023\/12\/IMG_20230921_091658-1-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2023\/12\/IMG_20230921_091658-1-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2023\/12\/IMG_20230921_091658-1-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2023\/12\/IMG_20230921_091658-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Aquesta frase va ser la primera que vam con\u00e8ixer de l&#8217;Antonio Ortega quan la tutora ens va mostrar a classe el document que parlava d&#8217;ell &#8230;. ENS AGRADA AQUESTA IDEA!!!! Vol dir que nosaltres tamb\u00e9 ho som&#8230;?????<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-302","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":4,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/302\/revisions"}],"predecessor-version":[{"id":310,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/302\/revisions\/310"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/media?parent=302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/categories?post=302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/tags?post=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}