{"id":425,"date":"2024-02-27T15:07:45","date_gmt":"2024-02-27T13:07:45","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/?p=425"},"modified":"2024-02-27T15:07:45","modified_gmt":"2024-02-27T13:07:45","slug":"pas-a-pas-fem-la-titella-a-la-vegada-que-creem-el-nostre-guio","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/pas-a-pas-fem-la-titella-a-la-vegada-que-creem-el-nostre-guio\/","title":{"rendered":"Pas a pas fem la titella, a la vegada que creem el nostre gui\u00f3&#8230;."},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"430\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094401-1024x768.jpg\" alt=\"\" class=\"wp-image-430\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094401-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094401-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094401-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094401-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094401-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"428\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094416-1024x768.jpg\" alt=\"\" class=\"wp-image-428\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094416-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094416-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094416-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094416-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094416-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"429\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094427-1024x768.jpg\" alt=\"\" class=\"wp-image-429\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094427-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094427-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094427-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094427-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_094427-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"426\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102001-768x1024.jpg\" alt=\"\" class=\"wp-image-426\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102001-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102001-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102001-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102001-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102001-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"427\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102009-768x1024.jpg\" alt=\"\" class=\"wp-image-427\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102009-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102009-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102009-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102009-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240201_102009-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"432\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092210-1024x768.jpg\" alt=\"\" class=\"wp-image-432\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092210-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092210-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092210-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092210-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092210-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"433\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092246-768x1024.jpg\" alt=\"\" class=\"wp-image-433\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092246-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092246-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092246-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092246-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092246-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"431\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092308-768x1024.jpg\" alt=\"\" class=\"wp-image-431\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092308-768x1024.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092308-225x300.jpg 225w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092308-1152x1536.jpg 1152w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092308-1536x2048.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/02\/IMG_20240222_092308-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-425","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/comments?post=425"}],"version-history":[{"count":1,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/425\/revisions"}],"predecessor-version":[{"id":434,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/425\/revisions\/434"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/media?parent=425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/categories?post=425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/tags?post=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}