{"id":496,"date":"2024-05-30T10:43:40","date_gmt":"2024-05-30T08:43:40","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/?p=496"},"modified":"2024-05-30T10:43:40","modified_gmt":"2024-05-30T08:43:40","slug":"ha-arribat-el-moment-a-la-sala-zumzeig-anem-a-presentar-les-nostres-histories","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/ha-arribat-el-moment-a-la-sala-zumzeig-anem-a-presentar-les-nostres-histories\/","title":{"rendered":"Ha arribat el moment&#8230;..a la sala ZUMZEIG anem a presentar les nostres hist\u00f2ries!"},"content":{"rendered":"\n<p><strong><em>LLUMS, TITELLES I ACCI\u00d3 ! ! ! !<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"499\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180656-1024x768.jpg\" alt=\"\" class=\"wp-image-499\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180656-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180656-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180656-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180656-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180656-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180957-1-1024x768.jpg\" alt=\"\" class=\"wp-image-500\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180957-1-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180957-1-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180957-1-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180957-1-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_180957-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_181208-1-1024x768.jpg\" alt=\"\" class=\"wp-image-501\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_181208-1-1024x768.jpg 1024w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_181208-1-300x225.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_181208-1-768x576.jpg 768w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_181208-1-1536x1152.jpg 1536w, https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-content\/uploads\/2024\/05\/IMG_20240527_181208-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Davant del nostre p\u00fablic (fam\u00edlies, professors, artista, mediadors i representants de les institucions) agra\u00efm l&#8217;oportunitat de fer aquest projecte i tot el que ens ha perm\u00e8s aprendre i gaudir amb la seva realitzaci\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LLUMS, TITELLES I ACCI\u00d3 ! ! ! ! Davant del nostre p\u00fablic (fam\u00edlies, professors, artista, mediadors i representants de les institucions) agra\u00efm l&#8217;oportunitat de fer aquest projecte i tot el que ens ha perm\u00e8s aprendre i gaudir amb la seva realitzaci\u00f3.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-496","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/comments?post=496"}],"version-history":[{"count":1,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/496\/revisions"}],"predecessor-version":[{"id":502,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/posts\/496\/revisions\/502"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/media?parent=496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/categories?post=496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/vallhebron2024\/wp-json\/wp\/v2\/tags?post=496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}