{"id":871,"date":"2024-02-19T23:30:45","date_gmt":"2024-02-19T21:30:45","guid":{"rendered":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/?p=871"},"modified":"2024-03-03T17:58:51","modified_gmt":"2024-03-03T15:58:51","slug":"primeres-impressions-despres-de-la-sessio-del-professorat","status":"publish","type":"post","link":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/primeres-impressions-despres-de-la-sessio-del-professorat\/","title":{"rendered":"Primeres impressions despr\u00e9s de la sessi\u00f3 del professorat"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"995\" height=\"564\" src=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/dillunsprofessorat14.jpg\" alt=\"\" class=\"wp-image-847\" srcset=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/dillunsprofessorat14.jpg 995w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/dillunsprofessorat14-300x170.jpg 300w, https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-content\/uploads\/2024\/02\/dillunsprofessorat14-768x435.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHa sigut molt divertit\u00bb <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMe he sentido muy c\u00f3modo presentando la exposici\u00f3n frente a los professores\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHa sigut guai quan els professors han comen\u00e7at a teixir \u00ab<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEm sento molt orgull\u00f3s pel treball que hem fet\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abM&#8217;ha agradat quan hem parlat amb els professors dels telers que hem construit\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00c9s molt divertit explicar coses en catal\u00e0 per\u00f2 tamb\u00e9 estava una mica nervi\u00f3s\u00bb <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstava  nerviosa i contenta\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abRecordo quan els professors flipaven amb el teixit fet de fil de paper\u00bb <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMe sent\u00eda un poco nervioso; estaban todos los profesores y por primera vez los alumnos haciendo clase\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstava nervi\u00f3s, i satisfet quan se n&#8217;han anat\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u00abM&#8217;han dit que ho he fet molt b\u00e9\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abHa sigut molt divertit\u00bb \u00abMe he sentido muy c\u00f3modo presentando la exposici\u00f3n frente a los professores\u00bb \u00abHa sigut guai quan els professors han comen\u00e7at a teixir \u00ab \u00abEm sento molt orgull\u00f3s pel treball que hem fet\u00bb \u00abM&#8217;ha agradat quan hem parlat amb els professors dels telers que hem construit\u00bb \u00ab\u00c9s molt divertit explicar coses en &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/primeres-impressions-despres-de-la-sessio-del-professorat\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abPrimeres impressions despr\u00e9s de la sessi\u00f3 del professorat\u00bb<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-871","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/posts\/871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/comments?post=871"}],"version-history":[{"count":4,"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/posts\/871\/revisions"}],"predecessor-version":[{"id":875,"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/posts\/871\/revisions\/875"}],"wp:attachment":[{"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/media?parent=871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/categories?post=871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blocsenresidencia.bcn.cat\/moli2024\/wp-json\/wp\/v2\/tags?post=871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}